{"id":439,"date":"2021-03-06T09:54:12","date_gmt":"2021-03-06T08:54:12","guid":{"rendered":"http:\/\/www.residenceflower.it\/?page_id=439"},"modified":"2023-05-31T22:21:54","modified_gmt":"2023-05-31T20:21:54","slug":"home","status":"publish","type":"page","link":"https:\/\/www.residenceflower.it\/it","title":{"rendered":"Residence Flower &gt; Appartamenti estivi Igea Marina con vista Mare"},"content":{"rendered":"<section class=\"l-section wpb_row height_auto width_full\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t\t\t<!-- START home 1 REVOLUTION SLIDER 6.6.13 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_10_1_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:transparent;padding:0;margin:0px auto;margin-top:0;margin-bottom:0;\">\n\t\t\t\t<rs-module id=\"rev_slider_10_1\" style=\"\" data-version=\"6.6.13\">\n\t\t\t\t\t<rs-slides style=\"overflow: hidden; position: absolute;\">\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-37\" data-title=\"Slide\" data-thumb=\"\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/spiaggia-ombrelloni.jpg\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.residenceflower.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" title=\"spiaggia-ombrelloni\" width=\"1920\" height=\"1280\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/spiaggia-ombrelloni.jpg\" data-bg=\"p:center bottom;\" data-no-retina>\n<!---->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-34\" data-title=\"Slide\" data-thumb=\"\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/bellaria-porto-header-1.jpg\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.residenceflower.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" title=\"-bellaria-porto-header\" width=\"1920\" height=\"920\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/bellaria-porto-header-1.jpg\" data-bg=\"p:center bottom;\" data-no-retina>\n<!---->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-38\" data-title=\"Slide\" data-thumb=\"\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/spiaggia-tramonto.jpg\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.residenceflower.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" title=\"spiaggia-tramonto\" width=\"1920\" height=\"1273\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/spiaggia-tramonto.jpg\" data-no-retina>\n<!---->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script>\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_10_1',rl:[1240,1024,778,480],el:[700],gw:[1240],gh:[700],type:'standard',justify:'',layout:'fullwidth',mh:\"0\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider101\"]!==undefined) {window.RS_MODULES.modules[\"revslider101\"].once = false;window.revapi10 = undefined;if (window.RS_MODULES.checkMinimal!==undefined) window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n<\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_08ec58de height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-separator size_small\"><\/div><div class=\"wpb_text_column us_custom_f8ac945f\"><div class=\"wpb_wrapper\"><h1 style=\"color: #32dab0; text-align: center; margin-bottom: 0;\">Appartamenti estivi a Igea Marina, vicini al Mare<\/h1>\n<h3 style=\"text-align: center; color: #fff;\">Residence Flower, a soli 70 metri dalla spiaggia, dotato di tutti i comfort<\/h3>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-tabs layout_hor style_default switch_click has_scrolling\" style=\"--sections-title-size:1em\"><div class=\"w-tabs-list items_5 align_none\"><div class=\"w-tabs-list-h\"><button class=\"w-tabs-item active\" aria-controls=\"content-ub4f\" aria-expanded=\"false\"><span class=\"w-tabs-item-title\">Tipo A Trilocale 65mq<\/span><\/button><button class=\"w-tabs-item\" aria-controls=\"content-ib02\" aria-expanded=\"false\"><span class=\"w-tabs-item-title\">Tipo B Bilocale 30mq<\/span><\/button><button class=\"w-tabs-item\" aria-controls=\"content-lae5\" aria-expanded=\"false\"><span class=\"w-tabs-item-title\">Tipo C Bilocale 30mq<\/span><\/button><button class=\"w-tabs-item\" aria-controls=\"content-q6ea\" aria-expanded=\"false\"><span class=\"w-tabs-item-title\">Tipo D Quadrilocale 60mq<\/span><\/button><button class=\"w-tabs-item\" aria-controls=\"content-z10d\" aria-expanded=\"false\"><span class=\"w-tabs-item-title\">Tipo E Attico 60mq<\/span><\/button><\/div><\/div><div class=\"w-tabs-sections titles-align_none icon_chevron cpos_right\"><div class=\"w-tabs-section active\" id=\"ub4f\"><button class=\"w-tabs-section-header active\" aria-controls=\"content-ub4f\" aria-expanded=\"true\"><div class=\"w-tabs-section-title\">Tipo A Trilocale 65mq<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-ub4f\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-image align_center\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/flower08-camera-coppia-1024x682.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/flower08-camera-coppia-1024x682.jpg 1024w, https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/flower08-camera-coppia-300x200.jpg 300w, https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/flower08-camera-coppia-600x400.jpg 600w, https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/flower08-camera-coppia.jpg 1348w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Trilocale di 65 mq con servizi privati e balconi indipendenti. Ampio, luminoso e attrezzato con angolo cottura e cucina con stoviglie.<\/p>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><ul>\n<li>trilocale di 65 mq<\/li>\n<li>2 camere matrimonialie, angolo cottura e 1 bagno<\/li>\n<li>max 4-6 persone<\/li>\n<li>aria condizionata indipendente in ogni stanza<\/li>\n<li>smart TV con connessione a Netflix, Prime, Sky<\/li>\n<li>terrazzo con veranda<\/li>\n<\/ul>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><div class=\"w-btn-wrapper align_none\"><a class=\"w-btn us-btn-style_3\" title=\"Appartamento tipo A per Famiglie Igea Marina\" href=\"https:\/\/www.residenceflower.it\/it\/appartamento-family-igea-marina.html\"><span class=\"w-btn-label\">Guarda Appartamento tipo A<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"ib02\"><button class=\"w-tabs-section-header\" aria-controls=\"content-ib02\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Tipo B Bilocale 30mq<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-ib02\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-image align_center\"><a title=\"appartemento B Igea Marina per Coppie\" href=\"http:\/\/www.residenceflower.it\/it\/appartemento-b-igea-marina-per-coppie\/\" aria-label=\"flower20-camera-donna-pc\" class=\"w-image-h\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/flower20-camera-donna-pc-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/flower20-camera-donna-pc-1024x683.jpg 1024w, https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/flower20-camera-donna-pc-300x200.jpg 300w, https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/flower20-camera-donna-pc-600x400.jpg 600w, https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/flower20-camera-donna-pc.jpg 1348w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><strong>Bilocale di 30 mq<\/strong>, giovane e allegro. Completo di angolo cottura attrezzato con stoviglie, servizi privati e balcone indipendente. <\/p>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><ul>\n<li>Bilocale di 30 mq<\/li>\n<li>1 camere matrimoniale, angolo cottura e 1 bagno<\/li>\n<li>max 2-3 persone<\/li>\n<li>aria condizionata indipendente in ogni stanza<\/li>\n<li>smart TV con connessione a Netflix, Prime, Sky<\/li>\n<\/ul>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><div class=\"w-btn-wrapper align_none\"><a class=\"w-btn us-btn-style_3\" title=\"Appartamento tipo A per Famiglie Igea Marina\" href=\"http:\/\/www.residenceflower.it\/it\/appartemento-b-igea-marina-per-coppie.html\"><span class=\"w-btn-label\">Guarda Appartamento tipo B<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"lae5\"><button class=\"w-tabs-section-header\" aria-controls=\"content-lae5\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Tipo C Bilocale 30mq<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-lae5\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-image align_center\"><a title=\"Appartamento Bilocale Igea Marina 30mq\" href=\"http:\/\/www.residenceflower.it\/it\/appartamento-bilocale-igea-marina\/\" aria-label=\"flower37-camera-family\" class=\"w-image-h\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/flower37-camera-family-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/flower37-camera-family-1024x683.jpg 1024w, https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/flower37-camera-family-300x200.jpg 300w, https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/flower37-camera-family-600x400.jpg 600w, https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/flower37-camera-family.jpg 1348w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Bilocale di 30 mq con letto matrimoniale e letto singolo. Servizi privati, angolo cottura attrezzato con stoviglie.<\/p>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><ul>\n<li>Bilocale di 30 mq<\/li>\n<li>1 camera matrimoniale, angolo cottura e 1 bagno<\/li>\n<li>max 2\/4 persone<\/li>\n<li>aria condizionata indipendente in ogni stanza<\/li>\n<li>smart TV con connessione a Netflix, Prime, Sky<\/li>\n<\/ul>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><div class=\"w-btn-wrapper align_none\"><a class=\"w-btn us-btn-style_3\" title=\"Appartamento tipo A per Famiglie Igea Marina\" href=\"http:\/\/www.residenceflower.it\/it\/appartamento-bilocale-igea-marina.html\"><span class=\"w-btn-label\">Guarda Appartamento tipo C<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"q6ea\"><button class=\"w-tabs-section-header\" aria-controls=\"content-q6ea\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Tipo D Quadrilocale 60mq<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-q6ea\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-image align_center\"><a title=\"Appartamento D Quadrilocale di Igea Marina di 60 mq\" href=\"http:\/\/www.residenceflower.it\/it\/appartamentro-quadrilocale-igea-marina\/\" aria-label=\"flower12-camera-colazione\" class=\"w-image-h\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/flower12-camera-colazione-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/flower12-camera-colazione-1024x683.jpg 1024w, https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/flower12-camera-colazione-300x200.jpg 300w, https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/flower12-camera-colazione-600x400.jpg 600w, https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/flower12-camera-colazione.jpg 1348w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Quadrilocale di 60mq con balconi indipendenti. Tre camere matrimoniali, due bagni e ampia zona giorno con angolo cottura<\/p>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><ul>\n<li>Quadrilocale di 60 mq<\/li>\n<li>3 camere matrimonialie, angolo cottura e 2 bagni<\/li>\n<li>max 4\/7 persone<\/li>\n<li>aria condizionata indipendente in ogni stanza<\/li>\n<li>smart TV con connessione a Netflix, Prime, Sky<\/li>\n<\/ul>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><div class=\"w-btn-wrapper align_none\"><a class=\"w-btn us-btn-style_3\" title=\"Appartamento tipo A per Famiglie Igea Marina\" href=\"http:\/\/www.residenceflower.it\/it\/appartamentro-quadrilocale-igea-marina.html\"><span class=\"w-btn-label\">Guarda Appartamento tipo D<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"z10d\"><button class=\"w-tabs-section-header\" aria-controls=\"content-z10d\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Tipo E Attico 60mq<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-z10d\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-image align_center\"><a title=\"Appartamento D Quadrilocale di Igea Marina di 60 mq\" href=\"http:\/\/www.residenceflower.it\/it\/attico-igea-marina-per-vacanze-estive\/\" aria-label=\"flower32-terrazza-family\" class=\"w-image-h\"><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/flower32-terrazza-family-1024x682.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/flower32-terrazza-family-1024x682.jpg 1024w, https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/flower32-terrazza-family-300x200.jpg 300w, https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/flower32-terrazza-family-600x400.jpg 600w, https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/flower32-terrazza-family.jpg 1348w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Attico di 60mq con 2 camere matrimoniali, 2 bagni, ampia zona giorno, angolo cottura e terrazzo solarium che circonda l&#8217;appartamento. Migliore vista panoramica da mare a monte a un passo dalle nuvole.<\/p>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><ul>\n<li>Attico di 60 mq<\/li>\n<li>2 camere matrimonialie, ampia zona giorno, angolo cottura e 1 bagno<\/li>\n<li>max 4\/7 persone<\/li>\n<li>aria condizionata indipendente in ogni stanza<\/li>\n<li>smart TV con connessione a Netflix, Prime, Sky<\/li>\n<\/ul>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><div class=\"w-btn-wrapper align_none\"><a class=\"w-btn us-btn-style_3\" title=\"Appartamento tipo A per Famiglie Igea Marina\" href=\"https:\/\/www.residenceflower.it\/it\/attico-igea-marina-vacanze-estive.html\"><span class=\"w-btn-label\">Guarda Appartamento tipo E<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_7fc3cf30 height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-separator size_small\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h1 style=\"color: #056c50; text-align: center; margin-bottom: 0;\">Affitti estivi a Igea Marina per le tue vacanze estive<\/h1>\n<h3 style=\"text-align: center; color: #fff;\">Scopri i nostri appartamenti e richiedi un preventivo personalizzato<\/h3>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-tabs style_default switch_click accordion has_scrolling\" style=\"--sections-title-size:inherit\"><div class=\"w-tabs-sections titles-align_none icon_plus cpos_right\"><div class=\"w-tabs-section\" id=\"i10e\"><button class=\"w-tabs-section-header with_icon\" aria-controls=\"content-i10e\" aria-expanded=\"false\"><i class=\"fas fa-bed\"><\/i><div class=\"w-tabs-section-title\">Il piacere di stare comodi<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-i10e\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-image align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/flower32-terrazza-family-1024x682.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/flower32-terrazza-family-1024x682.jpg 1024w, https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/flower32-terrazza-family-300x200.jpg 300w, https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/flower32-terrazza-family-600x400.jpg 600w, https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/flower32-terrazza-family.jpg 1348w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>La vacanza inizia quando metti piede in un appartamento che ti assomiglia. Che ha un buon odore. E sappia di pulito. Dove ci sono letti comodi, armadi grandi, una cucina con lavastoviglie e macchina per il caff\u00e8.<\/p>\n<p>E uno spazioso bagno con doccia e acqua calda per riprendersi dal viaggio. Inizia cos\u00ec la tua vacanza al mare, scegliendo il meglio e prendendoti cura di te e di chi ami. Appartamenti a 70 metri dalla spiaggia di Igea Marina, nel cuore del centro cittadino, vicino ai principali servizi, negozi e isola pedonale. Parcheggio privato, servizio Wi-Fi e ascensore. Bilocali, trilocali e attico: a te la scelta.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section active\" id=\"z888\"><button class=\"w-tabs-section-header active with_icon\" aria-controls=\"content-z888\" aria-expanded=\"true\"><i class=\"fas fa-umbrella-beach\"><\/i><div class=\"w-tabs-section-title\">A 70 metri dalla spiaggia<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-z888\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-image align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/spiaggia-ombrelloni-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/spiaggia-ombrelloni-1024x683.jpg 1024w, https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/spiaggia-ombrelloni-300x200.jpg 300w, https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/spiaggia-ombrelloni-600x400.jpg 600w, https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/spiaggia-ombrelloni.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>\u00c8 tra le pi\u00f9 conosciute, fotografate e immortalate dal cinema: la nostra spiaggia dalla sabbia dorata e dai granelli finissimi. Un litorale di 7 km di bellezza, di giovialit\u00e0 e simpatia. Ecco quello che trovi a Igea Marina.<\/p>\n<p>Un mare di divertimento. Lidi attrezzati, eventi notturni e diurni. La spiaggia diventa aggregazione, incontro, ritrovo fra amici e gioia. Non c\u2019\u00e8 luogo pi\u00f9 vissuto di questo. Amata dai bambini perch\u00e9 ha i fondali bassi. Apprezzata dai genitori perch\u00e9 sicura e con aree gioco dedicate. Scelta dai giovani per gli sport acquatici e il divertimento. Spiaggia convenzionata a 70 metri dagli appartamenti.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"h1f9\"><button class=\"w-tabs-section-header with_icon\" aria-controls=\"content-h1f9\" aria-expanded=\"false\"><i class=\"fas fa-car\"><\/i><div class=\"w-tabs-section-title\">Un mondo da scoprire<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-h1f9\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-image align_center\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/rocca-san-leo-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/rocca-san-leo-1024x683.jpg 1024w, https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/rocca-san-leo-300x200.jpg 300w, https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/rocca-san-leo-600x400.jpg 600w, https:\/\/www.residenceflower.it\/wp-content\/uploads\/2021\/03\/rocca-san-leo.jpg 1050w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Igea Marina \u00e8 conosciuta, ma l\u2019entroterra \u00e8 tutto da scoprire. C\u2019\u00e8 l\u2019intera Riviera Adriatica coi suoi borghi antichi, i castelli medievali, i paesi arroccati a picco su distese di verde incontaminato. C\u2019\u00e8 la storia di un territorio ricco di tradizioni, folklore, artigianato e cibo locale. Ci sono parchi naturali, riserve protette. Luoghi da visitare a piedi o in bicicletta. Per una gita fuori porta o una giornata all\u2019avventura. Santarcangelo di Romagna, San Leo, Gradera e il Parco nazionale delle foresti casentinesi. Colli, discese, laghi e parchi giochi. La Romagna \u00e8 questo, e molto altro ancora.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium color_alternate\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column us_custom_57354d11\"><div class=\"wpb_wrapper\"><p><em>I fratelli Del Vecchio sono stati carinissimi e disponibili, ci hanno anche dato la possibilit\u00e0 di rimanere qualche ora in pi\u00f9 per goderci l&#8217;ultima giornata di mare. L&#8217;appartamento dove abbiamo alloggiato \u00e8 molto ampio, luminoso, pulito e dotato di tutti i comfort. Vicinissimo alla spiaggia. Peccato che la vacanza sia durata troppo poco! \ud83d\ude42<\/em><\/p>\n<p>Monica Dedeu, <strong>recensione su google<\/strong>, 6 mesi fa<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column us_custom_57354d11\"><div class=\"wpb_wrapper\"><p><em>Per quanto concerne posizione,servizi e accoglienza eccellente. Un po&#8217; piu di attenzione x accessori domestici.Adatto x famiglie senza animali. Noi ci siamo trovati bene, tre adulti e due bambini.<\/em><\/p>\n<p>Tiziana Benini, <strong>recensione su google<\/strong>, 2 anni fa<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"Appartamenti estivi a Igea Marina, vicini al Mare Residence Flower, a soli 70 metri dalla spiaggia, dotato di tutti i comfort Tipo A Trilocale 65mqTipo B Bilocale 30mqTipo C Bilocale 30mqTipo D Quadrilocale 60mqTipo E Attico 60mqTipo A Trilocale 65mqTrilocale di 65 mq con servizi privati e balconi indipendenti. Ampio, luminoso e attrezzato con angolo...","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-439","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Residence Flower &gt; Appartamenti estivi Igea Marina con vista Mare<\/title>\n<meta name=\"description\" content=\"Residence flower Igea Marina con vista mare, a pochi passi dalla spiaggia. 5 appartamenti di 30 e 65 metri quadrati, bilocali, trilocali e quadrilocali. Appartamenti estivi in affitto a Bellaria Igea Marina.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.residenceflower.it\/it\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Residence Flower &gt; Appartamenti estivi Igea Marina con vista Mare\" \/>\n<meta property=\"og:description\" content=\"Residence flower Igea Marina con vista mare, a pochi passi dalla spiaggia. 5 appartamenti di 30 e 65 metri quadrati, bilocali, trilocali e quadrilocali. Appartamenti estivi in affitto a Bellaria Igea Marina.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.residenceflower.it\/it\" \/>\n<meta property=\"og:site_name\" content=\"Residence Flower\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-31T20:21:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.residenceflower.it\/it\",\"url\":\"https:\/\/www.residenceflower.it\/it\",\"name\":\"Residence Flower > Appartamenti estivi Igea Marina con vista Mare\",\"isPartOf\":{\"@id\":\"https:\/\/www.residenceflower.it\/it\/#website\"},\"datePublished\":\"2021-03-06T08:54:12+00:00\",\"dateModified\":\"2023-05-31T20:21:54+00:00\",\"description\":\"Residence flower Igea Marina con vista mare, a pochi passi dalla spiaggia. 5 appartamenti di 30 e 65 metri quadrati, bilocali, trilocali e quadrilocali. Appartamenti estivi in affitto a Bellaria Igea Marina.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.residenceflower.it\/it#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.residenceflower.it\/it\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.residenceflower.it\/it#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.residenceflower.it\/it\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Residence Flower &gt; Appartamenti estivi Igea Marina con vista Mare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.residenceflower.it\/it\/#website\",\"url\":\"https:\/\/www.residenceflower.it\/it\/\",\"name\":\"Residence Flower\",\"description\":\"Appartamenti estivi Igea Marina\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.residenceflower.it\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Residence Flower > Appartamenti estivi Igea Marina con vista Mare","description":"Residence flower Igea Marina con vista mare, a pochi passi dalla spiaggia. 5 appartamenti di 30 e 65 metri quadrati, bilocali, trilocali e quadrilocali. Appartamenti estivi in affitto a Bellaria Igea Marina.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.residenceflower.it\/it","og_locale":"it_IT","og_type":"article","og_title":"Residence Flower > Appartamenti estivi Igea Marina con vista Mare","og_description":"Residence flower Igea Marina con vista mare, a pochi passi dalla spiaggia. 5 appartamenti di 30 e 65 metri quadrati, bilocali, trilocali e quadrilocali. Appartamenti estivi in affitto a Bellaria Igea Marina.","og_url":"https:\/\/www.residenceflower.it\/it","og_site_name":"Residence Flower","article_modified_time":"2023-05-31T20:21:54+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.residenceflower.it\/it","url":"https:\/\/www.residenceflower.it\/it","name":"Residence Flower > Appartamenti estivi Igea Marina con vista Mare","isPartOf":{"@id":"https:\/\/www.residenceflower.it\/it\/#website"},"datePublished":"2021-03-06T08:54:12+00:00","dateModified":"2023-05-31T20:21:54+00:00","description":"Residence flower Igea Marina con vista mare, a pochi passi dalla spiaggia. 5 appartamenti di 30 e 65 metri quadrati, bilocali, trilocali e quadrilocali. Appartamenti estivi in affitto a Bellaria Igea Marina.","breadcrumb":{"@id":"https:\/\/www.residenceflower.it\/it#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.residenceflower.it\/it"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.residenceflower.it\/it#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.residenceflower.it\/it"},{"@type":"ListItem","position":2,"name":"Residence Flower &gt; Appartamenti estivi Igea Marina con vista Mare"}]},{"@type":"WebSite","@id":"https:\/\/www.residenceflower.it\/it\/#website","url":"https:\/\/www.residenceflower.it\/it\/","name":"Residence Flower","description":"Appartamenti estivi Igea Marina","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.residenceflower.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.residenceflower.it\/it\/wp-json\/wp\/v2\/pages\/439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.residenceflower.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.residenceflower.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.residenceflower.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.residenceflower.it\/it\/wp-json\/wp\/v2\/comments?post=439"}],"version-history":[{"count":54,"href":"https:\/\/www.residenceflower.it\/it\/wp-json\/wp\/v2\/pages\/439\/revisions"}],"predecessor-version":[{"id":762,"href":"https:\/\/www.residenceflower.it\/it\/wp-json\/wp\/v2\/pages\/439\/revisions\/762"}],"wp:attachment":[{"href":"https:\/\/www.residenceflower.it\/it\/wp-json\/wp\/v2\/media?parent=439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}